{"id":210,"count":1,"description":"","link":"https:\/\/rebeccabarger.com\/blog\/tag\/leigh-florist\/","name":"Leigh Florist","slug":"leigh-florist","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Leigh Florist Archives - Rebecca Barger Photography<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/rebeccabarger.com\/blog\/tag\/leigh-florist\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Leigh Florist Archives - Rebecca Barger Photography\" \/>\n<meta property=\"og:url\" content=\"https:\/\/rebeccabarger.com\/blog\/tag\/leigh-florist\/\" \/>\n<meta property=\"og:site_name\" content=\"Rebecca Barger Photography\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/rebeccabarger.com\\\/blog\\\/tag\\\/leigh-florist\\\/\",\"url\":\"https:\\\/\\\/rebeccabarger.com\\\/blog\\\/tag\\\/leigh-florist\\\/\",\"name\":\"Leigh Florist Archives - Rebecca Barger Photography\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.rebeccabarger.com\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/rebeccabarger.com\\\/blog\\\/tag\\\/leigh-florist\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/rebeccabarger.com\\\/blog\\\/tag\\\/leigh-florist\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.rebeccabarger.com\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Leigh Florist\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.rebeccabarger.com\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.rebeccabarger.com\\\/blog\\\/\",\"name\":\"Rebecca Barger Photography\",\"description\":\"Phila. photographer specializing in weddings, commercial, head shots\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.rebeccabarger.com\\\/blog\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.rebeccabarger.com\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.rebeccabarger.com\\\/blog\\\/#organization\",\"name\":\"Rebecca Barger Photography\",\"url\":\"https:\\\/\\\/www.rebeccabarger.com\\\/blog\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.rebeccabarger.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/rebeccabarger.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/RebeccaBargerPhoto-Logo-COLOR-e1555127969723.png\",\"contentUrl\":\"https:\\\/\\\/rebeccabarger.com\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/03\\\/RebeccaBargerPhoto-Logo-COLOR-e1555127969723.png\",\"width\":300,\"height\":183,\"caption\":\"Rebecca Barger Photography\"},\"image\":{\"@id\":\"https:\\\/\\\/www.rebeccabarger.com\\\/blog\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Leigh Florist Archives - Rebecca Barger Photography","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/rebeccabarger.com\/blog\/tag\/leigh-florist\/","og_locale":"en_US","og_type":"article","og_title":"Leigh Florist Archives - Rebecca Barger Photography","og_url":"https:\/\/rebeccabarger.com\/blog\/tag\/leigh-florist\/","og_site_name":"Rebecca Barger Photography","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/rebeccabarger.com\/blog\/tag\/leigh-florist\/","url":"https:\/\/rebeccabarger.com\/blog\/tag\/leigh-florist\/","name":"Leigh Florist Archives - Rebecca Barger Photography","isPartOf":{"@id":"https:\/\/www.rebeccabarger.com\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/rebeccabarger.com\/blog\/tag\/leigh-florist\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/rebeccabarger.com\/blog\/tag\/leigh-florist\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.rebeccabarger.com\/blog\/"},{"@type":"ListItem","position":2,"name":"Leigh Florist"}]},{"@type":"WebSite","@id":"https:\/\/www.rebeccabarger.com\/blog\/#website","url":"https:\/\/www.rebeccabarger.com\/blog\/","name":"Rebecca Barger Photography","description":"Phila. photographer specializing in weddings, commercial, head shots","publisher":{"@id":"https:\/\/www.rebeccabarger.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.rebeccabarger.com\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.rebeccabarger.com\/blog\/#organization","name":"Rebecca Barger Photography","url":"https:\/\/www.rebeccabarger.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.rebeccabarger.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/rebeccabarger.com\/blog\/wp-content\/uploads\/2019\/03\/RebeccaBargerPhoto-Logo-COLOR-e1555127969723.png","contentUrl":"https:\/\/rebeccabarger.com\/blog\/wp-content\/uploads\/2019\/03\/RebeccaBargerPhoto-Logo-COLOR-e1555127969723.png","width":300,"height":183,"caption":"Rebecca Barger Photography"},"image":{"@id":"https:\/\/www.rebeccabarger.com\/blog\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/rebeccabarger.com\/blog\/wp-json\/wp\/v2\/tags\/210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/rebeccabarger.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/rebeccabarger.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/rebeccabarger.com\/blog\/wp-json\/wp\/v2\/posts?tags=210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}